{"id":168,"date":"2023-01-04T10:30:00","date_gmt":"2023-01-04T09:30:00","guid":{"rendered":"https:\/\/medicalortho.fr\/blog\/?p=168"},"modified":"2025-01-29T14:36:06","modified_gmt":"2025-01-29T13:36:06","slug":"la-rhizarthrose-une-affection-douloureuse-et-handicapante","status":"publish","type":"post","link":"https:\/\/tousortho.fr\/blog\/orthopedie\/arthrose\/la-rhizarthrose-une-affection-douloureuse-et-handicapante\/","title":{"rendered":"La rhizarthrose, une affection douloureuse et handicapante"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Une pathologie qui touche principalement les femmes \u00e0 partir de 50 ans<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/medicalortho.fr\/blog\/wp-content\/uploads\/2023\/01\/Rhizarthrose-du-pouce-les-gestes-a-eviter-les-ortheses-a-privilegier-1024x576.jpg\" alt=\"Illustration de l'arthrose du pouce\" class=\"wp-image-170\" srcset=\"https:\/\/tousortho.fr\/blog\/wp-content\/uploads\/2023\/01\/Rhizarthrose-du-pouce-les-gestes-a-eviter-les-ortheses-a-privilegier-1024x576.jpg 1024w, https:\/\/tousortho.fr\/blog\/wp-content\/uploads\/2023\/01\/Rhizarthrose-du-pouce-les-gestes-a-eviter-les-ortheses-a-privilegier-300x169.jpg 300w, https:\/\/tousortho.fr\/blog\/wp-content\/uploads\/2023\/01\/Rhizarthrose-du-pouce-les-gestes-a-eviter-les-ortheses-a-privilegier-768x432.jpg 768w, https:\/\/tousortho.fr\/blog\/wp-content\/uploads\/2023\/01\/Rhizarthrose-du-pouce-les-gestes-a-eviter-les-ortheses-a-privilegier-1536x864.jpg 1536w, https:\/\/tousortho.fr\/blog\/wp-content\/uploads\/2023\/01\/Rhizarthrose-du-pouce-les-gestes-a-eviter-les-ortheses-a-privilegier.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">L&rsquo;arthrose du pouce ou rhizarthrose<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La<strong> rhizarthrose<\/strong> est le nom m\u00e9dical de <strong>l\u2019arthrose du pouce<\/strong>. Elle touche principalement la main la plus utilis\u00e9e, mais peut rapidement devenir bilat\u00e9rale, c\u2019est-\u00e0-dire touch\u00e9e les deux pouces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cartilages s\u2019usant avec le temps, les os en sont moins prot\u00e9g\u00e9s et le frottement d\u00fb aux mouvements du <strong>pouce<\/strong> entraine <strong>douleurs<\/strong> et incapacit\u00e9s. Elle peut \u00e9galement entrain\u00e9e des <strong>d\u00e9formations<\/strong> qui peuvent paraitre inesth\u00e9tiques, en plus d\u2019\u00eatre handicapantes. La <strong>douleur<\/strong> est particuli\u00e8rement sensible \u00e0 la <strong>base du pouce<\/strong> lors des mouvements, mais \u00e9galement durant la nuit. Au fil du temps, les personnes touch\u00e9es perdent en mobilit\u00e9 et en force.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce ph\u00e9nom\u00e8ne touche essentiellement les femmes \u00e0 partir de 50 ans, en raison de facteurs hormonaux. Des facteurs g\u00e9n\u00e9tiques peuvent intervenir, mais c\u2019est surtout le <strong>caract\u00e8re r\u00e9p\u00e9titif de certains gestes<\/strong>, li\u00e9 \u00e0 certains m\u00e9tiers, qui entraine son apparition.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le port d\u2019une attelle pour soulager les douleurs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En cas de <strong>douleurs intenses<\/strong> et handicapantes, le principal et premier traitement est m\u00e9dicamenteux et r\u00e9side dans la prise d\u2019antalgiques et d\u2019anti-inflammatoires. Mais une mise au repos de l\u2019<strong>articulation<\/strong> peut s\u2019av\u00e9rer tr\u00e8s efficace, de jour comme de nuit. En effet, le blocage du pouce avec une attelle sp\u00e9cifique emp\u00eachera tous mouvements douloureux et r\u00e9duira les risques de d\u00e9formation. Cette <strong>attelle<\/strong> peut \u00eatre r\u00e9alis\u00e9e sur mesure, mais vous retrouverez sur <a rel=\"noreferrer noopener\" href=\"https:\/\/medicalortho.fr\/fr\/39-pouce\" target=\"_blank\">notre site <\/a>une large gamme d\u2019<strong>attelle de s\u00e9rie<\/strong> qui r\u00e9pondra certainement au <strong>soulagement<\/strong> de votre <strong>rhizarthrose<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans certains cas, une intervention chirurgicale pourra vous \u00eatre propos\u00e9e, avec la mise en place d\u2019une proth\u00e8se. Elle sera suivie d\u2019une p\u00e9riode de r\u00e9\u00e9ducation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Retrouvez nos diff\u00e9rents mod\u00e8les ci-dessous<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-f56f613f wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/medicalortho.fr\/fr\/pouce\/143-1596-rhizoforte.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/medicalortho.fr\/436-medium_default\/rhizoforte.jpg\" alt=\"\"\/><\/a><figcaption class=\"wp-element-caption\">Orth\u00e8se Actimove Rhizoforte<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/medicalortho.fr\/fr\/pouce\/145-1910-manu-easy-pouce.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/medicalortho.fr\/532-medium_default\/manu-easy-pouce.jpg\" alt=\"\"\/><\/a><figcaption class=\"wp-element-caption\">Attelle Manu Easy pouce<\/figcaption><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Une pathologie qui touche principalement les femmes \u00e0 partir de 50 ans La rhizarthrose est le nom m\u00e9dical de l\u2019arthrose du pouce. Elle touche principalement la main la plus utilis\u00e9e, mais peut rapidement devenir bilat\u00e9rale, c\u2019est-\u00e0-dire touch\u00e9e les deux pouces. Les cartilages s\u2019usant avec le temps, les os en sont moins prot\u00e9g\u00e9s et le frottement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"La rhizarthrose l&#039;arthrose du pouce %%sep%% A propos de l&#039;orthop\u00e9die","_seopress_titles_desc":"La rhizarthrose est le nom m\u00e9dical de l\u2019arthrose du pouce. Elle touche principalement la main la plus utilis\u00e9e, mais peut rapidement devenir bilat\u00e9rale.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"rhizarthrose,arthrose du pouce,douleur pouce,d\u00e9formation pouce,attelle rhizarthrose","footnotes":""},"categories":[7],"tags":[9,30,29,32],"class_list":["post-168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arthrose","tag-arthrose","tag-arthrose-du-pouce","tag-rhizarthrose","tag-soulager-rhizarthrose"],"_links":{"self":[{"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/posts\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/comments?post=168"}],"version-history":[{"count":7,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/posts\/168\/revisions"}],"predecessor-version":[{"id":370,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/posts\/168\/revisions\/370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/media\/170"}],"wp:attachment":[{"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/media?parent=168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/categories?post=168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tousortho.fr\/blog\/wp-json\/wp\/v2\/tags?post=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}